{"id":6918,"date":"2026-07-15T09:24:52","date_gmt":"2026-07-15T09:24:52","guid":{"rendered":"https:\/\/vastgoedexperts.be\/?p=6918"},"modified":"2026-07-15T09:24:52","modified_gmt":"2026-07-15T09:24:52","slug":"les-10-defaillances-les-plus-courantes-lors-dune-inspection-electrique-dune-habitation","status":"publish","type":"post","link":"https:\/\/vastgoedexperts.be\/fr\/de-10-meest-voorkomende-inbreuken-bij-een-elektrische-keuring-van-een-woning\/","title":{"rendered":"Les 10 infractions les plus courantes lors d'une inspection \u00e9lectrique de domicile"},"content":{"rendered":"<h2>Les 10 infractions les plus courantes lors d'une inspection \u00e9lectrique de domicile<\/h2>\n<p>Un contr\u00f4le \u00e9lectrique est une \u00e9tape obligatoire lors de la vente d'une maison dont l'installation \u00e9lectrique a \u00e9t\u00e9 mise en service avant le 1er octobre 1981. Lors de ce contr\u00f4le, un organisme de contr\u00f4le agr\u00e9\u00e9 v\u00e9rifie si l'installation est conforme aux r\u00e9glementations en vigueur. <a href=\"https:\/\/economie.fgov.be\/nl\/publicaties\/algemeen-reglement-op-de\" target=\"_blank\" rel=\"noopener\">Livre 1 : Installations \u00e0 basse tension et tr\u00e8s basse.<\/a><\/p>\n<p>Au <strong>Vastgoedexperts <\/strong>Nous remarquons que de nombreux propri\u00e9taires se demandent quelles sont les 10 infractions les plus courantes lors d'une inspection \u00e9lectrique d'une habitation. Heureusement, bon nombre de ces infractions sont faciles \u00e0 r\u00e9soudre. Ci-dessous, nous dressons la liste des constatations les plus fr\u00e9quentes.<\/p>\n<ol>\n<li>\n<h2>Sch\u00e9ma unifilaire manquant ou incomplet<\/h2>\n<\/li>\n<\/ol>\n<p>L'une des remarques les plus courantes concerne l'absence d'un sch\u00e9ma unifilaire. Ce sch\u00e9ma indique la structure de l'installation \u00e9lectrique et les circuits pr\u00e9sents.<\/p>\n<p>M\u00eame lorsque le sch\u00e9ma ne correspond pas \u00e0 la situation r\u00e9elle, cela est consid\u00e9r\u00e9 comme une infraction.<\/p>\n<ol start=\"2\">\n<li>\n<h2>Sch\u00e9ma de situation manquant<\/h2>\n<\/li>\n<\/ol>\n<p>En dehors du sch\u00e9ma unifilaire, un sch\u00e9ma de situation est \u00e9galement obligatoire. Celui-ci indique l'emplacement des prises de courant, des interrupteurs, des points d'\u00e9clairage et des tableaux de distribution.<\/p>\n<p>De nombreux logements anciens ne disposent plus de ces plans, ce qui entra\u00eene automatiquement une \u00e9valuation n\u00e9gative de l'installation.<\/p>\n<ol start=\"3\">\n<li>\n<h2>Protection diff\u00e9rentielle insuffisante<\/h2>\n<\/li>\n<\/ol>\n<p>Les disjoncteurs diff\u00e9rentiels prot\u00e8gent les habitants contre les \u00e9lectrocutions et limitent les risques d'incendie.<\/p>\n<p>Souvent, l'inspecteur constate que :<\/p>\n<ul>\n<li>qu'il n'y a pas de diff\u00e9rentiel principal pr\u00e9sent\u00a0;<\/li>\n<li>le diff\u00e9rentiel suppl\u00e9mentaire obligatoire de 30 mA est absent pour les pi\u00e8ces humides;<\/li>\n<li>le diff\u00e9rentiel pr\u00e9sent ne r\u00e9pond pas aux normes actuelles (type et sensibilit\u00e9 corrects).<\/li>\n<\/ul>\n<ol start=\"4\">\n<li>\n<h2>Mise \u00e0 la terre insuffisante<\/h2>\n<\/li>\n<\/ol>\n<p>Une bonne mise \u00e0 la terre est essentielle pour la s\u00e9curit\u00e9 de l'installation \u00e9lectrique.<\/p>\n<p>Les probl\u00e8mes courants sont :<\/p>\n<ul>\n<li>pas de boucle de masse pr\u00e9sente ;<\/li>\n<li>r\u00e9sistance de dispersion trop \u00e9lev\u00e9e;<\/li>\n<li>prises de courant sans mise \u00e0 la terre fonctionnelle ;<\/li>\n<li>connexions \u00e9quipotentielles manquantes.<\/li>\n<\/ul>\n<ol start=\"5\">\n<li>\n<h2>Ouvertures dans le tableau \u00e9lectrique<\/h2>\n<\/li>\n<\/ol>\n<p>Un tableau de distribution doit \u00eatre enti\u00e8rement ferm\u00e9 afin que personne ne puisse entrer accidentellement en contact avec des composants sous tension.<\/p>\n<p>Les plaques de recouvrement manquantes ou les espaces ouverts dans le tableau \u00e9lectrique comptent parmi les commentaires les plus fr\u00e9quemment not\u00e9s.<\/p>\n<ol start=\"6\">\n<li>\n<h2>Identification insuffisante des circuits \u00e9lectriques<\/h2>\n<\/li>\n<\/ol>\n<p>Chaque fusible ou disjoncteur doit indiquer clairement quel est l'espace ou le circuit qu'il prot\u00e8ge.<\/p>\n<p>Lorsque les automates ne sont pas \u00e9tiquet\u00e9s ou sont incorrectement indiqu\u00e9s, l'inspecteur le note comme une infraction.<\/p>\n<ol start=\"7\">\n<li>\n<h2>Mat\u00e9riel \u00e9lectrique endommag\u00e9 ou obsol\u00e8te<\/h2>\n<\/li>\n<\/ol>\n<p>Lors de l'inspection, l'\u00e9tat g\u00e9n\u00e9ral de l'installation est \u00e9galement examin\u00e9.<\/p>\n<p>Par exemple :<\/p>\n<ul>\n<li>prises endommag\u00e9es ;<\/li>\n<li>commutateurs desserr\u00e9s;<\/li>\n<li>c\u00e2blage visible ou endommag\u00e9 ;<\/li>\n<li>fusibles ou tableaux de distribution obsol\u00e8tes.<\/li>\n<\/ul>\n<ol start=\"8\">\n<li>\n<h2>Prises sans protection pour enfants<\/h2>\n<\/li>\n<\/ol>\n<p>Lors de r\u00e9novations ou d'extensions, les prises \u00e9lectriques doivent \u00eatre conformes aux r\u00e9glementations de s\u00e9curit\u00e9 actuelles. Les anciennes prises sans protection enfant entra\u00eeneront automatiquement une infraction.<\/p>\n<ol start=\"9\">\n<li>\n<h2>Connexions mal r\u00e9alis\u00e9es<\/h2>\n<\/li>\n<\/ol>\n<p>Des connexions desserr\u00e9es, des bornes de soudure mal finies ou des raccordements non conformes sont r\u00e9guli\u00e8rement constat\u00e9s. Ces d\u00e9fauts augmentent le risque de surchauffe ou de court-circuit.<\/p>\n<ol start=\"10\">\n<li>\n<h2>Extensions non conformes<\/h2>\n<\/li>\n<\/ol>\n<p>Dans de nombreuses maisons, des prises de courant, des \u00e9clairages ou des annexes suppl\u00e9mentaires ont \u00e9t\u00e9 raccord\u00e9s au fil des ans sans que l'installation ne soit enti\u00e8rement conforme \u00e0 la r\u00e9glementation.<\/p>\n<p>De telles extensions entra\u00eenent souvent plusieurs manquements lors de l'inspection.<\/p>\n<h3>Qu'est-ce qu'un rapport de contr\u00f4le non conforme ?<\/h3>\n<p>Un rapport d'inspection non conforme ne signifie pas qu'une maison ne peut pas \u00eatre vendue. La vente peut se poursuivre normalement.<\/p>\n<p>L'acheteur est tenu, lorsque l'installation n'est pas conforme, de faire mettre en conformit\u00e9 l'installation \u00e9lectrique dans le d\u00e9lai l\u00e9galement pr\u00e9vu et de la faire contr\u00f4ler \u00e0 nouveau.<\/p>\n<p>Pour les vendeurs, il est donc souvent int\u00e9ressant de v\u00e9rifier au pr\u00e9alable quels d\u00e9fauts peuvent \u00eatre facilement r\u00e9solus. Un investissement limit\u00e9 peut non seulement conduire \u00e0 un rapport d'inspection plus favorable, mais aussi donner plus de confiance aux acheteurs potentiels.<\/p>\n<h3>D\u00e9cision<\/h3>\n<p>Un contr\u00f4le \u00e9lectrique ne doit pas \u00eatre un obstacle. La plupart des infractions concernent la documentation, la s\u00e9curit\u00e9 ou de petites d\u00e9faillances techniques qui peuvent \u00eatre r\u00e9solues relativement facilement.<\/p>\n<p>Au <strong>Vastgoedexperts<\/strong>\u00a0nous accompagnons les vendeurs et les acheteurs tout au long du processus de vente. Nous ne vous aidons pas seulement avec les attestations obligatoires, mais nous vous donnons \u00e9galement des conseils pratiques pour pr\u00e9parer au mieux votre bien immobilier \u00e0 une vente r\u00e9ussie.<\/p>\n<p><strong>Avez-vous des questions sur un <a href=\"https:\/\/vastgoedexperts.be\/fr\/linspection-de-votre-installation-electrique-sonti\/\">inspection \u00e9lectrique<\/a> ou si vous souhaitez savoir quels certificats sont n\u00e9cessaires lors de la vente de votre propri\u00e9t\u00e9 ? N'h\u00e9sitez pas <a href=\"https:\/\/vastgoedexperts.be\/fr\/contact\/\">Contactez<\/a> Appelez Vastgoedexperts. Nous sommes l\u00e0 pour vous aider.<\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>De 10 meest voorkomende inbreuken bij een elektrische keuring van een woning Een elektrische keuring is een verplicht onderdeel bij de verkoop van een woning waarvan de elektrische installatie v\u00f3\u00f3r 1 oktober 1981 in gebruik werd genomen. Tijdens deze keuring controleert een erkend keuringsorganisme of de installatie voldoet aan de geldende voorschriften van Boek 1: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3953,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[12],"tags":[],"class_list":["post-6918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elektrische-keuring"],"acf":[],"_links":{"self":[{"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/posts\/6918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/comments?post=6918"}],"version-history":[{"count":4,"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/posts\/6918\/revisions"}],"predecessor-version":[{"id":6925,"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/posts\/6918\/revisions\/6925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/media\/3953"}],"wp:attachment":[{"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/media?parent=6918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/categories?post=6918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vastgoedexperts.be\/fr\/wp-json\/wp\/v2\/tags?post=6918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}